{"id":79714,"date":"2023-11-02T12:23:14","date_gmt":"2023-11-02T11:23:14","guid":{"rendered":"https:\/\/www.diagonalmarcentre.es\/?post_type=tiendas&#038;p=79714"},"modified":"2025-03-14T11:16:57","modified_gmt":"2025-03-14T10:16:57","slug":"os-bar","status":"publish","type":"tiendas","link":"https:\/\/www.diagonalmarcentre.es\/ca\/botigues\/os-bar\/","title":{"rendered":"O&#8217;s Bar"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En el nou establiment, al qual es pot accedir sense necessitat de veure cap pel.licula, es poden consumir caf\u00e8s, pastissos i brioixos, cerveses i mes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el nou establiment, al qual es pot accedir sense necessitat de veure cap pel.licula, es poden consumir caf\u00e8s, pastissos i brioixos, cerveses i mes.<\/p>\n","protected":false},"author":8,"featured_media":79712,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"tiendas-category":[21,503],"class_list":["post-79714","tiendas","type-tiendas","status-publish","has-post-thumbnail","hentry","tiendas-category-restauracio","tiendas-category-cafeteries-gelateries-i-dolcos"],"featured_img_url":"https:\/\/www.diagonalmarcentre.es\/wp-content\/uploads\/2023\/11\/os-bar-diagonal-mar.svg","tiendas_category_array":["restauracio","cafeteries-gelateries-i-dolcos"],"custom_meta":{"local":"3680B","planta":"3","telf":"","id_neuro":"12283","reformas":""},"publishpress_future_action":{"enabled":false,"date":"2027-01-15 17:16:50","action":"category-remove","newStatus":"draft","terms":[],"taxonomy":"tiendas-category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.diagonalmarcentre.es\/ca\/wp-json\/wp\/v2\/tiendas\/79714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diagonalmarcentre.es\/ca\/wp-json\/wp\/v2\/tiendas"}],"about":[{"href":"https:\/\/www.diagonalmarcentre.es\/ca\/wp-json\/wp\/v2\/types\/tiendas"}],"author":[{"embeddable":true,"href":"https:\/\/www.diagonalmarcentre.es\/ca\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diagonalmarcentre.es\/ca\/wp-json\/wp\/v2\/comments?post=79714"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diagonalmarcentre.es\/ca\/wp-json\/wp\/v2\/media\/79712"}],"wp:attachment":[{"href":"https:\/\/www.diagonalmarcentre.es\/ca\/wp-json\/wp\/v2\/media?parent=79714"}],"wp:term":[{"taxonomy":"tiendas-category","embeddable":true,"href":"https:\/\/www.diagonalmarcentre.es\/ca\/wp-json\/wp\/v2\/tiendas-category?post=79714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}