{"id":71099,"date":"2026-06-08T07:00:00","date_gmt":"2026-06-08T05:00:00","guid":{"rendered":"https:\/\/www.diagonalmarcentre.es\/?p=71099"},"modified":"2026-06-03T16:29:53","modified_gmt":"2026-06-03T14:29:53","slug":"rebajas-en-rituals","status":"publish","type":"post","link":"https:\/\/www.diagonalmarcentre.es\/ca\/rebajas-en-rituals\/","title":{"rendered":"Rebajas de verano en Rituals"},"content":{"rendered":"\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Las Rebajas de Verano de <strong>Rituals <\/strong>ya est\u00e1n aqu\u00ed con <strong>descuentos de hasta un 50%<\/strong>!*&nbsp;<br><br>Es la oportunidad perfecta para conseguir tus imprescindibles a un precio especial y volver a comprar ediciones limitadas anteriores.<br><br>\u00bfQu\u00e9 productos no faltar\u00e1n en tu cesta de la compra?<br><br><strong>#ritualscosmetics<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>* El descuento solo es <strong>v\u00e1lido en art\u00edculos seleccionados<\/strong>. No se puede combinar con otras promociones. V\u00e1lido desde el <strong>15\/06\/2026 hasta el 26\/07\/2026<\/strong> o hasta fin de existencias. Los productos de la imagen pueden no coincidir con los incluidos en la promoci\u00f3n. Las ofertas pueden variar entre tiendas f\u00edsicas y tienda online.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Las Rebajas de Verano de Rituals ya est\u00e1n aqu\u00ed con descuentos de hasta un 50%!*&nbsp;Es la oportunidad perfecta para conseguir tus imprescindibles a un precio especial y volver a comprar ediciones limitadas anteriores.\u00bfQu\u00e9 productos no faltar\u00e1n en tu cesta de la compra?#ritualscosmetics * El descuento solo es v\u00e1lido en art\u00edculos seleccionados. No se puede combinar [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":91452,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_joinchat":[],"footnotes":""},"categories":[35],"tags":[],"class_list":["post-71099","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ofertas"],"featured_img_url":"https:\/\/www.diagonalmarcentre.es\/wp-content\/uploads\/2025\/01\/rituals-rebajas-verano-web.png","category_array":["ofertas"],"custom_meta":{"idTienda":"725","contentDirectorios":""},"publishpress_future_action":{"enabled":true,"date":"2026-07-26 23:50:00","action":"category","newStatus":"draft","terms":[861],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.diagonalmarcentre.es\/ca\/wp-json\/wp\/v2\/posts\/71099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diagonalmarcentre.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diagonalmarcentre.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diagonalmarcentre.es\/ca\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diagonalmarcentre.es\/ca\/wp-json\/wp\/v2\/comments?post=71099"}],"version-history":[{"count":0,"href":"https:\/\/www.diagonalmarcentre.es\/ca\/wp-json\/wp\/v2\/posts\/71099\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diagonalmarcentre.es\/ca\/wp-json\/wp\/v2\/media\/91452"}],"wp:attachment":[{"href":"https:\/\/www.diagonalmarcentre.es\/ca\/wp-json\/wp\/v2\/media?parent=71099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diagonalmarcentre.es\/ca\/wp-json\/wp\/v2\/categories?post=71099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diagonalmarcentre.es\/ca\/wp-json\/wp\/v2\/tags?post=71099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}